{"id":5794,"date":"2025-09-25T18:49:50","date_gmt":"2025-09-25T18:49:50","guid":{"rendered":"https:\/\/rotarygallaplacidia.it\/cms\/?p=5794"},"modified":"2025-09-29T18:55:27","modified_gmt":"2025-09-29T18:55:27","slug":"un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore","status":"publish","type":"post","link":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/","title":{"rendered":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?ssl=1\"><img fetchpriority=\"high\" decoding=\"async\" data-attachment-id=\"5795\" data-permalink=\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/livia-santini\/\" data-orig-file=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&amp;ssl=1\" data-orig-size=\"1500,2000\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Livia-Santini\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=225%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=750%2C1000&amp;ssl=1\" tabindex=\"0\" role=\"button\" src=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?resize=225%2C300&#038;ssl=1\" alt=\"\" width=\"225\" height=\"300\" class=\"alignnone size-medium wp-image-5795\" srcset=\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?w=1500&amp;ssl=1 1500w\" sizes=\"(max-width: 225px) 100vw, 225px\" data-recalc-dims=\"1\" \/><\/a><\/p>\n<p><strong>Gioved\u00ec 25 Settembre 2025 l\u2019Albergo del Cuore<\/strong>, la struttura di forte impatto sociale realizzata dalla Cooperativa sociale San Vitale, \u00e8 stata la giusta cornice che ha ospitato la \u00a0<strong>prof.ssa<\/strong> <strong>Livia Santini<\/strong>, che ha fatto della scuola e del volontariato la <em>mission <\/em>della sua vita.<\/p>\n<p>Nell\u2019Albergo lavorano attualmente 14 giovani diversamente abili che inizieranno ad accrescere il proprio bagaglio di capacit\u00e0 e competenze, famigliarizzando con gli spazi dell\u2019hotel e con le mansioni che andranno a svolgere.<\/p>\n<p>La prof.ssa Santini, che \u00e8 stata presentata dalla <strong>presidente<\/strong> del <strong>Rotary Club Ravenna Galla Placidia Elisa Mercuriali,<\/strong> ha spiegato le ragioni che l\u2019hanno portata a dedicarsi al volontariato assistenziale in ospedale a favore di malati gravi e bambini cardiopatici. Avendo un suo familiare che si trovava nella fase terminale della sua esistenza ha cercato di individuare formule che trasmettessero un\u2019assistenza psicologica che alleviasse i dolori della persona. Di qui \u00e8 nato il progetto \u201cRianimazione letteraria\u201d che ha portato anche al conferimento di un importante riconoscimento (cavalierato al merito nel settore del volontariato) da parte del Presidente della Repubblica nel corso del 2021.<\/p>\n<p>Sua \u00e8 stata anche l\u2019idea di organizzare le \u201cAlbe musicali\u201d per i bambini che hanno cardiopatie congenite, al fine di reperire fondi per l\u2019associazione. All\u2019interno dell\u2019Istituto Statale Morigia Perdisa \u00e8 stata la creatrice della Biblioteca e la conduttrice di programmi di lettura attiva con il coinvolgimento degli studenti.<\/p>\n<p>Foto: La Presidente del Rotary Ravenna Galla Palicidia Elisa Mercuriali e la Prof.ssa Livia Santini<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gioved\u00ec 25 Settembre 2025 l\u2019Albergo del Cuore, la struttura di forte impatto sociale realizzata dalla Cooperativa sociale San Vitale, \u00e8 stata la giusta cornice che ha ospitato la \u00a0prof.ssa Livia Santini, che ha fatto della scuola e del volontariato la mission della sua vita. Nell\u2019Albergo lavorano attualmente 14 giovani diversamente [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5795,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[14],"tags":[],"class_list":["post-5794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-distretto"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna\" \/>\n<meta property=\"og:description\" content=\"Gioved\u00ec 25 Settembre 2025 l\u2019Albergo del Cuore, la struttura di forte impatto sociale realizzata dalla Cooperativa sociale San Vitale, \u00e8 stata la giusta cornice che ha ospitato la \u00a0prof.ssa Livia Santini, che ha fatto della scuola e del volontariato la mission della sua vita. Nell\u2019Albergo lavorano attualmente 14 giovani diversamente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\" \/>\n<meta property=\"og:site_name\" content=\"Rotary Galla Placidia Ravenna\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T18:49:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T18:55:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Giovanni Montresori\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giovanni Montresori\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\"},\"author\":{\"name\":\"Giovanni Montresori\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/f41f18fc67fafc10843fedbb954ec5bb\"},\"headline\":\"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore\",\"datePublished\":\"2025-09-25T18:49:50+00:00\",\"dateModified\":\"2025-09-29T18:55:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\"},\"wordCount\":257,\"publisher\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#organization\"},\"image\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1\",\"articleSection\":[\"Distretto 2072\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\",\"url\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\",\"name\":\"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna\",\"isPartOf\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1\",\"datePublished\":\"2025-09-25T18:49:50+00:00\",\"dateModified\":\"2025-09-29T18:55:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1\",\"width\":1500,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/rotarygallaplacidia.it\/cms\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#website\",\"url\":\"https:\/\/rotarygallaplacidia.it\/cms\/\",\"name\":\"Rotary Galla Placidia Ravenna\",\"description\":\"Rotary Club Ravenna Galla Placidia\",\"publisher\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rotarygallaplacidia.it\/cms\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#organization\",\"name\":\"Rotary Galla Placidia Ravenna\",\"url\":\"https:\/\/rotarygallaplacidia.it\/cms\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2017\/05\/cropped-logo-5.png?fit=375%2C250&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2017\/05\/cropped-logo-5.png?fit=375%2C250&ssl=1\",\"width\":375,\"height\":250,\"caption\":\"Rotary Galla Placidia Ravenna\"},\"image\":{\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/f41f18fc67fafc10843fedbb954ec5bb\",\"name\":\"Giovanni Montresori\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3d9e7f1f9caad8f75087284e8e36637170492fa9e64342b174bfa0937df7ecda?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3d9e7f1f9caad8f75087284e8e36637170492fa9e64342b174bfa0937df7ecda?s=96&d=mm&r=g\",\"caption\":\"Giovanni Montresori\"},\"url\":\"https:\/\/rotarygallaplacidia.it\/cms\/author\/giovanni-montresori\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/","og_locale":"it_IT","og_type":"article","og_title":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna","og_description":"Gioved\u00ec 25 Settembre 2025 l\u2019Albergo del Cuore, la struttura di forte impatto sociale realizzata dalla Cooperativa sociale San Vitale, \u00e8 stata la giusta cornice che ha ospitato la \u00a0prof.ssa Livia Santini, che ha fatto della scuola e del volontariato la mission della sua vita. Nell\u2019Albergo lavorano attualmente 14 giovani diversamente [&hellip;]","og_url":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/","og_site_name":"Rotary Galla Placidia Ravenna","article_published_time":"2025-09-25T18:49:50+00:00","article_modified_time":"2025-09-29T18:55:27+00:00","og_image":[{"width":1500,"height":2000,"url":"https:\/\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg","type":"image\/jpeg"}],"author":"Giovanni Montresori","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giovanni Montresori","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#article","isPartOf":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/"},"author":{"name":"Giovanni Montresori","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/f41f18fc67fafc10843fedbb954ec5bb"},"headline":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore","datePublished":"2025-09-25T18:49:50+00:00","dateModified":"2025-09-29T18:55:27+00:00","mainEntityOfPage":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/"},"wordCount":257,"publisher":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/#organization"},"image":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1","articleSection":["Distretto 2072"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/","url":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/","name":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore - Rotary Galla Placidia Ravenna","isPartOf":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage"},"image":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1","datePublished":"2025-09-25T18:49:50+00:00","dateModified":"2025-09-29T18:55:27+00:00","breadcrumb":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#primaryimage","url":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1","width":1500,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/rotarygallaplacidia.it\/cms\/un-interessante-incontro-con-la-prof-ssa-livia-santini-presso-lalbergo-del-cuore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rotarygallaplacidia.it\/cms\/"},{"@type":"ListItem","position":2,"name":"Un interessante incontro con la prof.ssa Livia Santini presso l\u2019Albergo del Cuore"}]},{"@type":"WebSite","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#website","url":"https:\/\/rotarygallaplacidia.it\/cms\/","name":"Rotary Galla Placidia Ravenna","description":"Rotary Club Ravenna Galla Placidia","publisher":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rotarygallaplacidia.it\/cms\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#organization","name":"Rotary Galla Placidia Ravenna","url":"https:\/\/rotarygallaplacidia.it\/cms\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2017\/05\/cropped-logo-5.png?fit=375%2C250&ssl=1","contentUrl":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2017\/05\/cropped-logo-5.png?fit=375%2C250&ssl=1","width":375,"height":250,"caption":"Rotary Galla Placidia Ravenna"},"image":{"@id":"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/f41f18fc67fafc10843fedbb954ec5bb","name":"Giovanni Montresori","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/rotarygallaplacidia.it\/cms\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3d9e7f1f9caad8f75087284e8e36637170492fa9e64342b174bfa0937df7ecda?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3d9e7f1f9caad8f75087284e8e36637170492fa9e64342b174bfa0937df7ecda?s=96&d=mm&r=g","caption":"Giovanni Montresori"},"url":"https:\/\/rotarygallaplacidia.it\/cms\/author\/giovanni-montresori\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rotarygallaplacidia.it\/cms\/wp-content\/uploads\/2025\/09\/Livia-Santini.jpeg?fit=1500%2C2000&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8KQsN-1vs","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/posts\/5794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/comments?post=5794"}],"version-history":[{"count":1,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/posts\/5794\/revisions"}],"predecessor-version":[{"id":5796,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/posts\/5794\/revisions\/5796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/media\/5795"}],"wp:attachment":[{"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/media?parent=5794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/categories?post=5794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotarygallaplacidia.it\/cms\/wp-json\/wp\/v2\/tags?post=5794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}